{"id":2,"count":9,"description":"","link":"https:\/\/iempenang.org\/eetd\/category\/event\/","name":"eETD Event","slug":"event","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/iempenang.org\/eetd\/wp-json\/wp\/v2\/categories\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iempenang.org\/eetd\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/iempenang.org\/eetd\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/iempenang.org\/eetd\/wp-json\/wp\/v2\/posts?categories=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}